{"id":792,"date":"2009-01-15T12:03:20","date_gmt":"2009-01-15T12:03:20","guid":{"rendered":"http:\/\/willphillips.org.uk\/radio\/?p=792"},"modified":"2009-01-16T22:26:23","modified_gmt":"2009-01-16T22:26:23","slug":"wrcr","status":"publish","type":"post","link":"https:\/\/willphillips.org.uk\/radio\/wrcr\/","title":{"rendered":"WRCR"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/willphillips.org.uk\/radio\/wp-content\/uploads\/2009\/01\/wrcr1.jpg\" alt=\"WRCR QSL\" title=\"WRCR QSL\" width=\"550\" height=\"330\" class=\"size-full wp-image-793\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[93,86,110,99,44,118,3,87,119,104,27,89],"tags":[],"_links":{"self":[{"href":"https:\/\/willphillips.org.uk\/radio\/wp-json\/wp\/v2\/posts\/792"}],"collection":[{"href":"https:\/\/willphillips.org.uk\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/willphillips.org.uk\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/willphillips.org.uk\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/willphillips.org.uk\/radio\/wp-json\/wp\/v2\/comments?post=792"}],"version-history":[{"count":3,"href":"https:\/\/willphillips.org.uk\/radio\/wp-json\/wp\/v2\/posts\/792\/revisions"}],"predecessor-version":[{"id":999,"href":"https:\/\/willphillips.org.uk\/radio\/wp-json\/wp\/v2\/posts\/792\/revisions\/999"}],"wp:attachment":[{"href":"https:\/\/willphillips.org.uk\/radio\/wp-json\/wp\/v2\/media?parent=792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/willphillips.org.uk\/radio\/wp-json\/wp\/v2\/categories?post=792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/willphillips.org.uk\/radio\/wp-json\/wp\/v2\/tags?post=792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}