{"id":73,"date":"2009-01-02T20:15:09","date_gmt":"2009-01-02T20:15:09","guid":{"rendered":"http:\/\/localhost\/radioblog\/?p=73"},"modified":"2009-01-17T10:06:56","modified_gmt":"2009-01-17T10:06:56","slug":"europe-41","status":"publish","type":"post","link":"https:\/\/willphillips.org.uk\/radio\/europe-41\/","title":{"rendered":"Europe 41"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/willphillips.org.uk\/radio\/wp-content\/uploads\/2009\/01\/europe41.jpg\" alt=\"Europe 41 QSL\" title=\"Europe 41 QSL\" width=\"550\" height=\"358\" class=\"size-full wp-image-74\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[93,86,9,56,110,99,44,3,87,130,89],"tags":[],"_links":{"self":[{"href":"https:\/\/willphillips.org.uk\/radio\/wp-json\/wp\/v2\/posts\/73"}],"collection":[{"href":"https:\/\/willphillips.org.uk\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/willphillips.org.uk\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/willphillips.org.uk\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/willphillips.org.uk\/radio\/wp-json\/wp\/v2\/comments?post=73"}],"version-history":[{"count":4,"href":"https:\/\/willphillips.org.uk\/radio\/wp-json\/wp\/v2\/posts\/73\/revisions"}],"predecessor-version":[{"id":1141,"href":"https:\/\/willphillips.org.uk\/radio\/wp-json\/wp\/v2\/posts\/73\/revisions\/1141"}],"wp:attachment":[{"href":"https:\/\/willphillips.org.uk\/radio\/wp-json\/wp\/v2\/media?parent=73"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/willphillips.org.uk\/radio\/wp-json\/wp\/v2\/categories?post=73"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/willphillips.org.uk\/radio\/wp-json\/wp\/v2\/tags?post=73"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}