{"id":335,"date":"2009-01-12T18:24:19","date_gmt":"2009-01-12T18:24:19","guid":{"rendered":"http:\/\/willphillips.org.uk\/radio\/?p=335"},"modified":"2009-01-17T00:48:32","modified_gmt":"2009-01-17T00:48:32","slug":"kiwi-radio","status":"publish","type":"post","link":"https:\/\/willphillips.org.uk\/radio\/kiwi-radio\/","title":{"rendered":"KIWI Radio"},"content":{"rendered":"<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/willphillips.org.uk\/radio\/wp-content\/uploads\/2009\/01\/kiwi.jpg\" alt=\"KIWI Radio QSL\" title=\"KIWI Radio QSL\" width=\"550\" height=\"404\" class=\"size-full wp-image-336\" \/><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/willphillips.org.uk\/radio\/wp-content\/uploads\/2009\/01\/kiwi2.jpg\" alt=\"KIWI Radio sticker\" title=\"KIWI Radio sticker\" width=\"450\" height=\"239\" class=\"size-full wp-image-410\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[91,86,56,110,127,15,99,145,102,44,105,3,87,123,89],"tags":[],"_links":{"self":[{"href":"https:\/\/willphillips.org.uk\/radio\/wp-json\/wp\/v2\/posts\/335"}],"collection":[{"href":"https:\/\/willphillips.org.uk\/radio\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/willphillips.org.uk\/radio\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/willphillips.org.uk\/radio\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/willphillips.org.uk\/radio\/wp-json\/wp\/v2\/comments?post=335"}],"version-history":[{"count":5,"href":"https:\/\/willphillips.org.uk\/radio\/wp-json\/wp\/v2\/posts\/335\/revisions"}],"predecessor-version":[{"id":1137,"href":"https:\/\/willphillips.org.uk\/radio\/wp-json\/wp\/v2\/posts\/335\/revisions\/1137"}],"wp:attachment":[{"href":"https:\/\/willphillips.org.uk\/radio\/wp-json\/wp\/v2\/media?parent=335"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/willphillips.org.uk\/radio\/wp-json\/wp\/v2\/categories?post=335"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/willphillips.org.uk\/radio\/wp-json\/wp\/v2\/tags?post=335"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}